{"id":25237,"date":"2020-10-09T18:30:00","date_gmt":"2020-10-10T00:30:00","guid":{"rendered":"https:\/\/goldenti.com\/site\/?p=25237"},"modified":"2020-10-09T16:29:14","modified_gmt":"2020-10-09T22:29:14","slug":"belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g","status":"publish","type":"post","link":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/","title":{"rendered":"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G"},"content":{"rendered":"\n<p><em>Decisi\u00f3n tomada por presi\u00f3n de E.U, adem\u00e1s de la preocupaci\u00f3n de la seguridad pues el pa\u00eds alberga la OTAN y el parlamento de la UE.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/03\/5G-640x360.jpg\" alt=\"B\u00e9lgica_Nokia_Huawei_Estados_Unidos_Otan_UE_5G\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li><\/li><\/ul>\n\n\n\n<p><strong>Reuters.-<\/strong>&nbsp;<strong>Orange y Proximus eligieron a Nokia para que les ayude a construir redes de 5G en B\u00e9lgica<\/strong>, prescindiendo de Huawei en medio de la presi\u00f3n estadounidense para excluir a la firma china del suministro equipos de telecomunicaciones claves.<\/p>\n\n\n\n<p><strong>La decisi\u00f3n es una de las primeras entre los operadores comerciales europeos para dejar a Huawei fuera<\/strong>&nbsp;de las redes de pr\u00f3xima generaci\u00f3n y llegan tras meses de presi\u00f3n diplom\u00e1tica de Washington, que argumenta que los equipos de la compa\u00f1\u00eda china podr\u00edan ser usados por Pek\u00edn para espiar.<\/p>\n\n\n\n<p>La capital de B\u00e9lgica, Bruselas, alberga la sede de la OTAN y del Ejecutivo y el Parlamento de la Uni\u00f3n Europea, lo que<strong>&nbsp;le convierte en un asunto de especial preocupaci\u00f3n para las agencias de inteligencia estadounidenses.<\/strong><\/p>\n\n\n\n<p>\u201cB\u00e9lgica ha dependido en un&nbsp;<strong>100% de los vendedores chinos para sus redes de radio y la gente que trabaja en la OTAN y la UE<\/strong>&nbsp;estaba haciendo llamadas telef\u00f3nicas con esas redes\u201d, dijo John Strand, un consultor independiente dan\u00e9s de telecomunicaciones.<\/p>\n\n\n\n<p>\u201cLos operadores est\u00e1n enviando la se\u00f1al de que es importante tener acceso a redes seguras\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>Estados Unidos celebr\u00f3 las decisiones de Orange Belgium y Proximus, que tienen un acuerdo para compartir redes.<\/p>\n\n\n\n<p>\u201c<strong>Este es el \u00faltimo ejemplo de acuerdos de Huawei que se evaporan, as\u00ed como una nueva confirmaci\u00f3n de ese impulso mundial hacia los vendedores confiables<\/strong>\u201c, dijo Keith Krach, subsecretario del Departamento de Estado para crecimiento econ\u00f3mico, energ\u00eda y medio ambiente.<\/p>\n\n\n\n<p><strong>Huawei, el mayor proveedor mundial de equipos de telecomunicaciones, rechaza con fuerza las acusaciones estadounidenses<\/strong>\u00a0y ha criticado duramente los llamados a su exclusi\u00f3n de los contratos de 5G.<\/p>\n\n\n\n<p>Fuente: www.forbes.com.mx<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decisi\u00f3n tomada por presi\u00f3n de E.U, adem\u00e1s de la preocupaci\u00f3n de la seguridad pues el pa\u00eds [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":25238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G -\" \/>\n<meta property=\"og:description\" content=\"Decisi\u00f3n tomada por presi\u00f3n de E.U, adem\u00e1s de la preocupaci\u00f3n de la seguridad pues el pa\u00eds [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-10T00:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G\",\"datePublished\":\"2020-10-10T00:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/\"},\"wordCount\":345,\"image\":{\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/\",\"url\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/\",\"name\":\"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G -\",\"isPartOf\":{\"@id\":\"https:\/\/goldenti.com\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png\",\"datePublished\":\"2020-10-10T00:30:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage\",\"url\":\"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png\",\"contentUrl\":\"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png\",\"width\":860,\"height\":483},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/goldenti.com\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/goldenti.com\/site\/#website\",\"url\":\"https:\/\/goldenti.com\/site\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/goldenti.com\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/goldenti.com\/site\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/","og_locale":"es_ES","og_type":"article","og_title":"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G -","og_description":"Decisi\u00f3n tomada por presi\u00f3n de E.U, adem\u00e1s de la preocupaci\u00f3n de la seguridad pues el pa\u00eds [&hellip;]","og_url":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/","article_published_time":"2020-10-10T00:30:00+00:00","og_image":[{"width":860,"height":483,"url":"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#article","isPartOf":{"@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/"},"author":{"name":"","@id":""},"headline":"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G","datePublished":"2020-10-10T00:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/"},"wordCount":345,"image":{"@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage"},"thumbnailUrl":"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/","url":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/","name":"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G -","isPartOf":{"@id":"https:\/\/goldenti.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage"},"image":{"@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage"},"thumbnailUrl":"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png","datePublished":"2020-10-10T00:30:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#primaryimage","url":"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png","contentUrl":"https:\/\/goldenti.com\/site\/wp-content\/uploads\/2020\/10\/Captura-22.png","width":860,"height":483},{"@type":"BreadcrumbList","@id":"https:\/\/goldenti.com\/site\/belgica-deja-fuera-a-huawei-elige-a-nokia-para-levantar-su-red-5g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/goldenti.com\/site\/"},{"@type":"ListItem","position":2,"name":"B\u00e9lgica deja fuera a Huawei; elige a Nokia para levantar su red 5G"}]},{"@type":"WebSite","@id":"https:\/\/goldenti.com\/site\/#website","url":"https:\/\/goldenti.com\/site\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/goldenti.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"","url":"https:\/\/goldenti.com\/site\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/posts\/25237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/comments?post=25237"}],"version-history":[{"count":1,"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/posts\/25237\/revisions"}],"predecessor-version":[{"id":25239,"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/posts\/25237\/revisions\/25239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/media\/25238"}],"wp:attachment":[{"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/media?parent=25237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/categories?post=25237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goldenti.com\/site\/wp-json\/wp\/v2\/tags?post=25237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}